{"id":1390,"date":"2018-06-22T21:01:04","date_gmt":"2018-06-22T21:01:04","guid":{"rendered":"http:\/\/demensdeum.com\/blog\/?p=1390"},"modified":"2024-12-16T22:32:43","modified_gmt":"2024-12-16T19:32:43","slug":"games-vision-3","status":"publish","type":"post","link":"https:\/\/demensdeum.com\/blog\/fr\/2018\/06\/22\/games-vision-3\/","title":{"rendered":"Vision des jeux #3"},"content":{"rendered":"<p>Le troisi\u00e8me num\u00e9ro d&#8217;une chronique non permanente sur les jeux <strong>Games Vision<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1391\" src=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/observer.jpg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/observer.jpg 700w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/observer-300x169.jpg 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><a href=\"https:\/\/www.observer-game.com\/\" target=\"_blank\" rel=\"noopener\">Observer<\/a> (PC et consoles, Bloober Team) &#8211; horreur cyberpunk des vaillants Polonais. Un film d&#8217;horreur court et tr\u00e8s atmosph\u00e9rique avec Rutger Hauer. En tant que fan de cyberpunk, j\u2019ai absolument tout aim\u00e9 du jeu. Des \u00e9nigmes pas tr\u00e8s difficiles, des p\u00e9pins charmants du personnage principal, un gameplay avec des moments calmes m\u00eal\u00e9s d&#8217;action, la possibilit\u00e9 de se plonger litt\u00e9ralement dans les souvenirs des morts, une intrigue de style Ghost in the Shell + de nombreuses r\u00e9f\u00e9rences \u00e0 la culture pop Sci-Fi. Parmi les inconv\u00e9nients &#8211; trop de probl\u00e8mes, il semble parfois qu&#8217;en raison de leur abondance, il est impossible de jouer, et certains joueurs \u00e9taient \u00e9galement enrag\u00e9s par des \u00e9l\u00e9ments d&#8217;horreur sp\u00e9cifiques qui \u00e9taient si effrayants qu&#8217;ils ne pouvaient pas continuer \u00e0 jouer.<br \/>Note\u00a0: <strong>8\/10<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1393\" src=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/glammetal.jpg\" alt=\"\" width=\"692\" height=\"389\" srcset=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/glammetal.jpg 1920w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/glammetal-300x169.jpg 300w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/glammetal-768x432.jpg 768w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/glammetal-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 692px) 100vw, 692px\" \/><\/p>\n<p><a href=\"https:\/\/www.paradigmadventure.com\/\" target=\"_blank\" rel=\"noopener\">Paradigm<\/a> (Windows\/OS X, Jacob Janerka) &#8211; une qu\u00eate qui parvient \u00e0 parodier et \u00e0 rire de tout \u00e0 la fois. Il y a le ridicule de l&#8217;URSS, de l&#8217;Am\u00e9rique, du genre qu\u00eate, du glam rock, des vieilles consoles, des gens, des monuments, des informaticiens, des c\u00f4nes, des ordinateurs, des femmes, des enfants, des parents, des artistes, de l&#8217;amour, des scientifiques, de l&#8217;industrie du jeu, des joueurs eux-m\u00eames et #8211\u00a0; En g\u00e9n\u00e9ral, il est impossible de tout \u00e9num\u00e9rer. Intrigue absolument impr\u00e9visible, atmosph\u00e8re et art absurdes, \u00e9nigmes pas particuli\u00e8rement difficiles. Le jeu pr\u00e9sente de rares bugs et crashs, certains moments et blagues sont l\u00e9g\u00e8rement pr\u00e9visibles et non originaux.<br \/>Note\u00a0: <strong>9\/10<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1397\" src=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/lateshift.jpg\" alt=\"\" width=\"695\" height=\"291\" srcset=\"https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/lateshift.jpg 1024w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/lateshift-300x126.jpg 300w, https:\/\/demensdeum.com\/blog\/wp-content\/uploads\/2018\/06\/lateshift-768x322.jpg 768w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><\/p>\n<p><a href=\"http:\/\/lateshift-movie.com\" target=\"_blank\" rel=\"noopener\">Late Shift<\/a>\u00a0(PC et consoles, CtrlMovie Ltd) &#8211; film interactif. Je suis vraiment d\u00e9sol\u00e9 qu&#8217;une id\u00e9e fondamentalement bonne ait \u00e9t\u00e9 si mal mise en \u0153uvre. Tout va mal &#8211; intrigue, manque d&#8217;acteurs vedettes, jeu d&#8217;acteurs, blocages constants dans la version PC, variabilit\u00e9 presque nulle (illusoire). Il est totalement incompr\u00e9hensible comment il a \u00e9t\u00e9 possible de sortir un jeu avec autant de probl\u00e8mes dans les ann\u00e9es 2010, car en fait il s&#8217;agit d&#8217;un lecteur vid\u00e9o ordinaire, le jeu entier aurait pu \u00eatre publi\u00e9 sur Internet, par exemple sur YouTube, mais \u00e0 la place ils ont utilis\u00e9 Unity et a r\u00e9ussi \u00e0 briser m\u00eame un moteur de jeu aussi puissant. Le forum officiel sur Steam est d\u00e9di\u00e9 aux correctifs, hotfix, solutions de contournement, etc. Il y a une catastrophe technique, manque de support utilisateur, tous les tests se font directement sur les joueurs. J&#8217;ai achet\u00e9 des critiques et des t\u00e9moignages \u00e9logieux.<br \/>Note\u00a0: <strong>3\/10<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le troisi\u00e8me num\u00e9ro d&#8217;une chronique non permanente sur les jeux Games Vision. Observer (PC et consoles, Bloober Team) &#8211; horreur cyberpunk des vaillants Polonais. Un film d&#8217;horreur court et tr\u00e8s atmosph\u00e9rique avec Rutger Hauer. En tant que fan de cyberpunk, j\u2019ai absolument tout aim\u00e9 du jeu. Des \u00e9nigmes pas tr\u00e8s difficiles, des p\u00e9pins charmants du<a class=\"more-link\" href=\"https:\/\/demensdeum.com\/blog\/fr\/2018\/06\/22\/games-vision-3\/\">Continue reading <span class=\"screen-reader-text\">&#8220;Vision des jeux #3&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[49,65],"tags":[67],"class_list":["post-1390","post","type-post","status-publish","format-standard","hentry","category-blog","category-games-vision","tag-gamesvision","entry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"fr","enabled_languages":["en","ru","zh","de","fr","ja","pt","hi"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"zh":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":false,"content":false,"excerpt":false}}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/1390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/comments?post=1390"}],"version-history":[{"count":15,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/1390\/revisions"}],"predecessor-version":[{"id":3980,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/posts\/1390\/revisions\/3980"}],"wp:attachment":[{"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/media?parent=1390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/categories?post=1390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/fr\/wp-json\/wp\/v2\/tags?post=1390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}