{"id":4348,"date":"2026-04-22T08:54:55","date_gmt":"2026-04-22T05:54:55","guid":{"rendered":"https:\/\/demensdeum.com\/blog\/2026\/04\/22\/raspberry-pi-3-as-router\/"},"modified":"2026-04-23T09:39:06","modified_gmt":"2026-04-23T06:39:06","slug":"raspberry-pi-3-as-router","status":"publish","type":"post","link":"https:\/\/demensdeum.com\/blog\/pt\/2026\/04\/22\/raspberry-pi-3-as-router\/","title":{"rendered":"Raspberry PI 3 como roteador Wi-Fi"},"content":{"rendered":"<p>Existem muitos artigos na Internet sobre como fazer um roteador Wi-Fi a partir de um Raspberry Pi (RPI). Neste post descreverei brevemente meu m\u00e9todo de cria\u00e7\u00e3o de um roteador Wi-Fi com uma caixa \u00fanica integrada. O m\u00e9todo descrito funciona no momento e muita coisa pode mudar no futuro. Portanto, use esta nota como uma vis\u00e3o geral do que voc\u00ea enfrentar\u00e1.<\/p>\n<h3>SSH<\/h3>\n<p>Para quem n\u00e3o sabe trabalhar com OpenWrt, recomendo instalar dietPI.<br \/>\nConecte o RPI ao seu roteador atual via eth0 e, em seguida, conecte-o via SSH. Voc\u00ea pode descobrir o endere\u00e7o IP RPI no painel DHCP do roteador. Conecte-se diretamente ao root, por exemplo assim:<\/p>\n<div class=\"hcb_wrap\">\n<pre class=\"prism line-numbers lang-unknown\" data-lang=\"unknown\"><code>ssh root@[IP_ADDRESS]\n<\/code><\/pre>\n<\/div>\n<h3>Ponto de acesso<\/h3>\n<p>A senha dietPI padr\u00e3o para root \u00e9 dietpi. Uma vez conectado, voc\u00ea ser\u00e1 recebido pelo instalador\/configurador dietPI. Quando terminar, voc\u00ea precisar\u00e1 se conectar novamente devido \u00e0 reinicializa\u00e7\u00e3o do dispositivo.<\/p>\n<p>Primeiro, voc\u00ea precisa configurar o hostapd para que os dispositivos possam ver seu ponto de acesso. Se o hostapd n\u00e3o estiver instalado, instale-o via apt.<\/p>\n<p>Em seguida, voc\u00ea precisar\u00e1 escrever uma configura\u00e7\u00e3o para o hostapd. Exemplo da minha configura\u00e7\u00e3o:<\/p>\n<div class=\"hcb_wrap\">\n<pre class=\"prism line-numbers lang-unknown\" data-lang=\"unknown\"><code>interface=wlan0\ndriver=nl80211\nssid=MyPiAP\nhw_mode=a\nchannel=157\nwmm_enabled=1\n\nauth_algs=1\nwpa=2\nwpa_passphrase=your_password\nwpa_key_mgmt=WPA-PSK\nrsn_pairwise=CCMP\nieee80211n=1\nieee80211ac=0\nieee80211ax=0\ncountry_code=RU\n<\/code><\/pre>\n<\/div>\n<p>O significado da configura\u00e7\u00e3o do hostapd pode ser encontrado no manual. Por\u00e9m, o importante \u00e9 configurar voc\u00ea mesmo &#8211; o canal (2,4 GHz ou 5 GHz), o c\u00f3digo do pa\u00eds, caso contr\u00e1rio sem isso seus dispositivos localizados podem funcionar corretamente com o ponto de acesso, eu j\u00e1 fiz isso e sei, ent\u00e3o certifique-se de definir seu pa\u00eds.<\/p>\n<h3>DHCP<\/h3>\n<p>Em seguida, instale e configure o dnsmasq para implementar o DHCP. Isso \u00e9 necess\u00e1rio para que os computadores conectados determinem o endere\u00e7o IP e o servidor DNS.<br \/>\nExemplo da minha configura\u00e7\u00e3o:<\/p>\n<div class=\"hcb_wrap\">\n<pre class=\"prism line-numbers lang-unknown\" data-lang=\"unknown\"><code>interface=wlan0\ndhcp-range=172.19.0.10,172.19.0.200,255.255.255.0,12h\n\ndhcp-option=3,172.19.0.1\n\ndhcp-option=6,1.1.1.1,8.8.8.8\n\nno-resolv\n\nserver=1.1.1.1\nserver=8.8.8.8\n<\/code><\/pre>\n<\/div>\n<p>Esta \u00e9 a configura\u00e7\u00e3o m\u00ednima que permitir\u00e1 conectar-se a um ponto de acesso e obter um endere\u00e7o IP. Em seguida, voc\u00ea precisar\u00e1 configurar o roteamento e o NAT. Isso \u00e9 necess\u00e1rio para que os computadores conectados possam acessar a Internet.<\/p>\n<p>Aqui a nota vai para a categoria de configura\u00e7\u00e3o t\u00edpica de roteamento em um sistema regular compat\u00edvel com Debian, sobre a qual existem muitos artigos na Internet. Ent\u00e3o tudo depende de quais objetivos voc\u00ea est\u00e1 perseguindo, por exemplo, conectar-se a um servidor externo como uma nova interface no sistema, ou apenas fazer wlan0 <-> eth0, \u00e9 aqui que terminam as especifica\u00e7\u00f5es do RPI, depois configure-o ao seu gosto.<\/p>\n<p>Gostaria tamb\u00e9m de mencionar a necessidade de configurar servi\u00e7os personalizados do sistema via systemctl; pode haver necessidade de conectar servi\u00e7os em uma cadeia; tudo isso est\u00e1 nos manuais do systemctl na rede. Se houver problemas no n\u00edvel de servi\u00e7o, verifique os logs no journalctl.<\/p>\n<h3>Adaptador Wi-Fi<\/h3>\n<p>O RPI3 integrado revelou-se francamente fraco e n\u00e3o suporta 5GHz. Portanto, conectei o adaptador RITMIX RWA-150 no chipset Realtek RTL8811CU via USB 2. Os drivers foram adicionados ao kernel Linux que estava na minha vers\u00e3o dietPi. Em seguida, usando dietpi-config, desliguei completamente o Wi-Fi integrado. Como resultado, sobrou apenas um adaptador USB wlan0.<\/p>\n<h3>Conclus\u00e3o<\/h3>\n<p>A partir das medi\u00e7\u00f5es de velocidade, conseguimos extrair cerca de 50 Mbps do RPI3 via Wi-Fi (ap\u00f3s conectar um adaptador de 5 GHz), o que significa uma perda de metade da velocidade em compara\u00e7\u00e3o com a conex\u00e3o direta ao roteador. Admito que modelos RPI mais produtivos permitir\u00e3o obter melhores resultados, tamb\u00e9m dispositivos OpenWrt especializados e solu\u00e7\u00f5es prontas podem ser melhores para suas necessidades.<\/p>\n<h3>Fontes<\/h3>\n<p><a href=\"https:\/\/forums.raspberrypi.com\/viewtopic.php?t=394710\" rel=\"noopener\" target=\"_blank\">https:\/\/forums.raspberrypi.com\/viewtopic.php?t=394710<\/a><br \/>\n<a href=\"https:\/\/superuser.com\/questions\/1408586\/raspberry-pi-wifi-hotspot-slow-internet-speed\" rel=\"noopener\" target=\"_blank\">https:\/\/superuser.com\/questions\/1408586\/raspberry-pi-wifi-hotspot-slow-internet-speed<\/a><br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=jlHWnKVpygw\" rel=\"noopener\" target=\"_blank\">https:\/\/www.youtube.com\/watch?v=jlHWnKVpygw<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existem muitos artigos na Internet sobre como fazer um roteador Wi-Fi a partir de um Raspberry Pi (RPI). Neste post descreverei brevemente meu m\u00e9todo de cria\u00e7\u00e3o de um roteador Wi-Fi com uma caixa \u00fanica integrada. O m\u00e9todo descrito funciona no momento e muita coisa pode mudar no futuro. Portanto, use esta nota como uma vis\u00e3o<a class=\"more-link\" href=\"https:\/\/demensdeum.com\/blog\/pt\/2026\/04\/22\/raspberry-pi-3-as-router\/\">Continue reading <span class=\"screen-reader-text\">&#8220;Raspberry PI 3 como roteador Wi-Fi&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-4348","post","type-post","status-publish","format-standard","hentry","category-techie","entry"],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"pt","enabled_languages":["en","ru","zh","de","fr","ja","pt","hi"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"ru":{"title":true,"content":true,"excerpt":false},"zh":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":true,"content":true,"excerpt":false},"ja":{"title":true,"content":true,"excerpt":false},"pt":{"title":true,"content":true,"excerpt":false},"hi":{"title":false,"content":false,"excerpt":false}}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/4348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/comments?post=4348"}],"version-history":[{"count":4,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/4348\/revisions"}],"predecessor-version":[{"id":4352,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/4348\/revisions\/4352"}],"wp:attachment":[{"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/media?parent=4348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/categories?post=4348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/demensdeum.com\/blog\/pt\/wp-json\/wp\/v2\/tags?post=4348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}